{"id":11264,"date":"2023-12-13T14:02:42","date_gmt":"2023-12-13T13:02:42","guid":{"rendered":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/?p=11264"},"modified":"2025-12-19T15:26:25","modified_gmt":"2025-12-19T14:26:25","slug":"h2-ready-gasheizungen-check","status":"publish","type":"post","link":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/","title":{"rendered":"H<sub>2<\/sub>-ready-Gasheizungen im Check"},"content":{"rendered":"\n<p><ul>\n<li><a href=\"#h2-ready-heizung\">Was hei\u00dft H<sub>2<\/sub>-ready eigentlich?<\/a><\/li>\n<li><a href=\"#vorteil-wasserstoff-heizung\">Vorteile des Heizens mit Wasserstoff in H<sub>2<\/sub>-ready-Heizungen<\/a><\/li>\n<li><a href=\"#wasserstoff-potenzial-waermewende\">Welches Potenzial hat der Einsatz von Wasserstoff f\u00fcr die W\u00e4rmewende?<\/a><\/li><\/ul>\n<ol><li><a href=\"#herausforderungen-h2-ready-gasheizungen\">Herausforderungen von H<sub>2<\/sub>-ready-Gasheizungen, die 100 % wasserstofff\u00e4hig sind<\/a><\/li>\n<li><a href=\"#wasserstoff-verfuegbarkeit-preise\">Verf\u00fcgbarkeit und Preise von gr\u00fcnem Wasserstoff<\/a><\/li>\n<li><a href=\"#wasserstoff-umstellung-gasverteilnetz\">Umstellung des Gasverteilernetzes auf 100 % Wasserstoff<\/a><\/li><\/ol><ul>\n<li><a href=\"#zukunft-h2-ready-gasheizung\">Fazit: Zukunft von H2-ready-Gasheizungen als Alternative<\/a><\/li>\n<\/ul><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bis 2045 soll Deutschland klimaneutral<\/strong> sein. Neben dem Ausbau der Erneuerbaren Energien spielt dabei die <strong>Transformation des W\u00e4rmesektors<\/strong> eine entscheidende Rolle. Immerhin werden etwa 50 % der Endenergie verwendet, um H\u00e4user und Wohnungen zu heizen.<sup data-fn=\"bba35717-12f7-4773-99a8-959f058267af\" class=\"fn\"><a href=\"#bba35717-12f7-4773-99a8-959f058267af\" id=\"bba35717-12f7-4773-99a8-959f058267af-link\">1<\/a><\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Rahmen der <strong>Neugestaltung des GEG<\/strong> wurde ein neuer Gesetzentwurf verabschiedet. Urspr\u00fcnglich sollten ab 1. Januar 2024 nur noch neue Heizungen eingebaut werden, die mit <strong>mindestens 65 % Erneuerbaren Energien<\/strong> betrieben werden.<sup data-fn=\"1c696975-4cac-4707-a8d5-46a4806ffc8c\" class=\"fn\"><a href=\"#1c696975-4cac-4707-a8d5-46a4806ffc8c\" id=\"1c696975-4cac-4707-a8d5-46a4806ffc8c-link\">2<\/a><\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Vorgabe h\u00e4tte eigentlich das Aus f\u00fcr die klassische Gasheizung bedeutet, die aktuell zu 100 % auf den fossilen Brennstoff Erdgas setzt. Allerdings sieht das reformierte Geb\u00e4udeenergiegesetz jetzt <strong><a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/geg-heizungsgesetz-waermepumpe-gas-kosten\/\">Ausnahmen f\u00fcr den Einbau neuer Gasheizungen f\u00fcr Bestandsgeb\u00e4ude und Neubauten<\/a> au\u00dferhalb von Neubaugebieten<\/strong> vor. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funktionierende Heizungen k\u00f6nnen Stand heute (Dezember 2023) bis Ende 2044 weiterbetrieben werden, sofern es sich nicht um 30 Jahre alte \u00d6l- und Gaskessel handelt. Zwischen 2024 und dem Inkrafttreten der kommunalen W\u00e4rmeplanung sind auch neue Gasheizungen erlaubt, die dann jedoch ansteigend Erneuerbare Energien integrieren m\u00fcssen: 15 % bereits im Jahr 2029, 30 % in 2035 und mindestens 60 % in 2040. Alternativ sind auch Gas-Hybridheizungen eine Option.<sup data-fn=\"d8310f31-7bd5-4369-b061-4bcc39ea617a\" class=\"fn\"><a href=\"#d8310f31-7bd5-4369-b061-4bcc39ea617a\" id=\"d8310f31-7bd5-4369-b061-4bcc39ea617a-link\">3<\/a><\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem k\u00f6nnen Gasheizungen auch weiterhin eingebaut werden, wenn sie:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>zuk\u00fcnftig mindestens <strong><a href=\"https:\/\/www.erdgas-suedwest.de\/privatkunden\/gastarife\/gas-bio65?ctm_source=blog&amp;ctm_medium=esw&amp;ctm_campaign=h2-ready-gasheizungen-check&amp;ctm_content=text\" rel=\"noreferrer noopener\">65 % mit erneuerbaren Energien<\/a><\/strong> betrieben werden oder<\/li>\n\n\n\n<li><strong>H<sub>2<\/sub>-ready <\/strong>sind, also auf Wasserstoff umger\u00fcstet werden k\u00f6nnen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die 65-%-Vorgabe erf\u00fcllen unter anderem <a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/hybridheizung-vorteil-altbau\/\">Hybridheizungen<\/a>. Diese kombinieren zum Beispiel einen Gasbrennwertkessel mit einer <a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/waermepumpe-heizung-arten-funktion\/\">W\u00e4rmepumpe<\/a>, einer <a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/fragen-solarthermie\/\">Solarthermieanlage<\/a> oder einer Biomasseheizung, wie einer Pellet- oder Hackschnitzelheizung. Auch eine normale Gasbrennwertheizung kann weiterhin im Bestand oder Neubau au\u00dferhalb Neubaugebieten eingebaut werden, wenn Sie mit einem 65 % Biogas-Tarif des Energieversorgers beheizt wird. <\/p>\n\n\n\n<div class=\"responsive-two-columns\">\n\t<div class=\"c1\">\n\t\t<a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/hybridheizung?ctm_source=blog&#038;ctm_medium=esw&#038;ctm_campaign=h2-ready-gasheizungen-check&#038;ctm_content=banner\" rel=\"noopener\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/hybridheizung-e1702457538556.jpg\" alt=\"Hybridheizung Gasbrennwertheizung W\u00e4rmepumpe\" \/>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"c2\">\n\t\t<h3>Hybridheizung \u2013 intelligent kombiniert<\/h3>\n\t\t<p>Optimal versorgt mit Gasheizung und W\u00e4rmepumpe oder Solarthermie.<\/p>\n\t\t<a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/hybridheizung?ctm_source=blog&#038;ctm_medium=esw&#038;ctm_campaign=h2-ready-gasheizungen-check&#038;ctm_content=banner\" class=\"button\" rel=\"noopener\">Jetzt informieren!<\/a>\n\t<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"h2-ready-heizung\" class=\"sprung\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Was hei\u00dft H<sub>2<\/sub>-ready eigentlich?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Gegensatz zur klassischen Gasheizung ist eine H<sub>2<\/sub>-ready-Gasheizung \u2013 wie der Name anzeigt \u2013 <strong>bereit f\u00fcr den Einsatz von Wasserstoff<\/strong>. Abh\u00e4ngig vom Heizungsmodell darf in einer aktuell verf\u00fcgbaren H<sub>2<\/sub>-ready-Gasheizung ein Erdgasgemisch eingesetzt werden, das <strong>bis zu 20 Volumenprozent (Vol. %) aus Wasserstoff<\/strong> besteht. Um das H<sub>2<\/sub>-ready-Siegel zu erhalten, das vom Deutschen Verein des Gas- und Wasserfaches (DVGW) vergeben wird, muss die Heizung ein entsprechendes Zertifizierungsverfahren durchlaufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Hauptunterschied zwischen einer klassischen Gasheizung und einer H<sub>2<\/sub>-ready-Gasheizung ist also der <strong>eingesetzte Brennstoff<\/strong>. Ansonsten \u00e4hnelt ein H<sub>2<\/sub>-ready-Heizkessel in seiner Funktionsweise einem klassischen Gasbrennwertkessel. Dieser besteht aus Brenner, Brennraum, W\u00e4rme\u00fcbertr\u00e4ger und Abgasrohr: Durch die Verbrennung des Gasgemisches im Brenner entsteht W\u00e4rme. Diese wird \u00fcber den W\u00e4rme\u00fcbertr\u00e4ger an das Heizwasser gegeben, um anschlie\u00dfend mit einer Umw\u00e4lzpumpe \u00fcber ein Rohrsystem an die Heizk\u00f6rper verteilt zu werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um m\u00f6glichst effizient zu arbeiten, werden die entstehenden Abgase durch einen zweiten W\u00e4rmetauscher weitergeleitet, bis Wasserdampf kondensiert. Bei der Kondensation gibt das vorher gasf\u00f6rmige Wasser W\u00e4rmeenergie ab, mit der das Heizwasser vorgew\u00e4rmt wird. Dadurch erreichen <a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/gasbrennwertheizung\">Ga<\/a><a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/gasbrennwertheizung?ctm_source=blog&amp;ctm_medium=esw&amp;ctm_campaign=h2-ready-gasheizungen-check&amp;ctm_content=text\" rel=\"noreferrer noopener\">sbrennwertheizungen<\/a> und somit auch H<sub>2<\/sub>-ready-Gasheizungen einen <strong>Wirkungsgrad von bis zu 98 %<\/strong> und sind dadurch besonders energieeffizient.<\/p>\n\n\n\n<div id=\"vorteil-wasserstoff-heizung\" class=\"sprung\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Vorteile des Heizens mit Wasserstoff in H<sub>2<\/sub>-ready-Heizungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der gro\u00dfe Vorteil beim Heizen mit Wasserstoff ist, dass beim Verbrennen des Gases im Gegensatz zum Verbrennen von Erdgas <strong>kein Kohlenstoffdioxid (CO<sub>2<\/sub>)<\/strong>, sondern in erster Linie Wasser entsteht. Werden beim Herstellungsprozess zum Beispiel im Rahmen der Wasserelektrolyse bei gr\u00fcnem Wasserstoff Erneuerbare Energien eingesetzt, ist auch dieser Prozess CO<sub>2<\/sub>-neutral.<\/p>\n\n\n\n<div style=\"padding-top:40px;padding-right:40px;padding-bottom:40px;padding-left:40px\" class=\"wp-block-editor-blocks-wrapper alignfull infobox\"><div class=\"wrapper-inner\"><div class=\"wrapper-inner-blocks\">\n<h3 class=\"wp-block-heading\">Die verschiedenen Herstellungsverfahren von Wasserstoff im \u00dcberblick<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wasserstoff l\u00e4sst sich auf verschiedene Arten gewinnen. Es handelt sich um ein farbloses Gas. Trotzdem wird von grauem, blauem, t\u00fcrkisem oder vor allem gr\u00fcnem Wasserstoff gesprochen. Anhand der Einteilung in Farben sollen die <strong>verschiedenen Herstellungsarten<\/strong> und das damit verbundene <strong>Ma\u00df an Klimaneutralit\u00e4t<\/strong> deutlich werden:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-1024x724.png\" alt=\"Infografik Farbenlehre Wasserstoff\" class=\"wp-image-2806\" srcset=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-1024x724.png 1024w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-300x212.png 300w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-768x543.png 768w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-1536x1086.png 1536w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-2048x1449.png 2048w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-480x340.png 480w, https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2020\/09\/infografik-wasserstoff-farbenlehre-975x690.png 975w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus ist Wasserstoff zumindest theoretisch <strong>nahezu unbegrenzt verf\u00fcgbar<\/strong>, l\u00e4sst sich <strong>einfach speichern<\/strong> und voraussichtlich auch <strong>\u00fcber das bestehende Gasnetz transportieren<\/strong>. Dazu sp\u00e4ter mehr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiterer Vorteil vom Heizen mit Wasserstoff sind die <strong>g\u00fcnstigen Kosten f\u00fcr eine H<sub>2<\/sub>-ready-Gasheizung<\/strong>. Diese unterscheiden sich kaum von den Preisen regul\u00e4rer Gasheizungen. Eine <strong>H<sub>2<\/sub>-ready-Gastherme<\/strong> gibt es abh\u00e4ngig vom Modell f\u00fcr etwa <strong>4.000 bis 7.000 Euro<\/strong>. Die <strong>Umbaukosten<\/strong>, inkl. Wassertank und Pumpe, liegen bei etwa <strong>11.000 bis 13.000 Euro<\/strong>. Insgesamt ist also mit <strong>Gesamtkosten zwischen 15.000 und 20.000 Euro<\/strong> zu rechnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Vergleich zu den <a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/waermepumpe-heizung-kosten-foerderung\/\">Kosten f\u00fcr eine W\u00e4rmepumpe<\/a>, die zum Beispiel bei der g\u00fcnstigsten Variante, der Luft-Wasser-W\u00e4rmepumpe, bei 30.000 bis 45.000 Euro startet, ist der Umstieg auf eine H<sub>2<\/sub>-ready-Gasheizung recht g\u00fcnstig.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Heizungstyp<\/th><th>Anschaffungskosten<\/th><th>Installationskosten<\/th><th>Gesamtkosten<\/th><\/tr><\/thead><tbody><tr><td>H<sub>2<\/sub>-ready-Gastherme<\/td><td>4.000 bis 7.000 Euro<\/td><td>11.000 bis 13.000 Euro (inkl. Wassertank, Pumpe etc.)<\/td><td>15.000 bis 20.000 Euro<\/td><\/tr><tr><td>Luft-Wasser-W\u00e4rmepumpe<\/td><td>20.000 bis 30.000 Euro<\/td><td>10.000 bis 15.000 Euro<\/td><td>30.000 bis 45.000 Euro<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"responsive-two-columns\">\n\t<div class=\"c1\">\n\t\t<a href=\"\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/gasbrennwertheizung?ctm_source=blog&#038;ctm_medium=esw&#038;ctm_campaign=h2-ready-gasheizungen-check&#038;ctm_content=banner\" rel=\"noopener\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/08\/Gasbrennwertheizung_Heizungswechsel_3x2.jpg\" alt=\"Heizungswechsel schnell und einfach\" \/>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"c2\">\n\t\t<h3>Gasheizung mit 100% H2-ready-Potenzial<\/h3>\n\t\t<p>Jetzt zuverl\u00e4ssig und zukunftssicher heizen!<\/p>\n\t\t<a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/gasbrennwertheizung?ctm_source=blog&#038;ctm_medium=esw&#038;ctm_campaign=h2-ready-gasheizungen-check&#038;ctm_content=banner\" class=\"button\" rel=\"noopener\">Informieren und Angebot anfordern<\/a>\n\t<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div id=\"wasserstoff-potenzial-waermewende\" class=\"sprung\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Welches Potenzial hat der Einsatz von Wasserstoff f\u00fcr die W\u00e4rmewende?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Auf den ersten Blick scheint der Einsatz von Wasserstoff in H<sub>2<\/sub>-ready-Gasheizungen also durchaus Potenzial zu haben. Immerhin sind sowohl die Gewinnung als auch die Verbrennung von Wasserstoff grunds\u00e4tzlich ohne den Aussto\u00df von CO<sub>2<\/sub> m\u00f6glich. Und auch die Kosten einer H<sub>2<\/sub>-ready-Heizung sind im Vergleich zu anderen Heizungsarten \u00fcberschaubar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Welche Rolle die Technologie bei der W\u00e4rmewende spielen wird, h\u00e4ngt allerdings ma\u00dfgeblich von <strong>drei Faktoren<\/strong> <strong>bzw. Voraussetzungen<\/strong> ab:<\/p>\n\n\n\n<div id=\"herausforderungen-h2-ready-gasheizungen\" class=\"sprung\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1. Herausforderungen von H<sub>2<\/sub>-ready-Gasheizungen, die 100 % wasserstofff\u00e4hig sind<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im Zuge des reformierten Geb\u00e4udeenergiegesetzes <strong>d\u00fcrfen auch neue H<sub>2<\/sub>-ready-Gasheizungen eingebaut werden<\/strong>. <strong>Ausnahmen stellen Neubauten in Neubaugebieten<\/strong> dar, in denen ab 1. Januar 2024 weder neue Gas- noch \u00d6lheizungen erlaubt sind. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr alle anderen Geb\u00e4ude gelten <strong>bis zum Vorliegen einer sogenannten kommunalen W\u00e4rmeplanung nahezu keine Einschr\u00e4nkungen<\/strong> \u2013 sogar der Einbau von \u00d6lheizungen bleibt eine Option. Die kommunale W\u00e4rmeplanung muss in Abh\u00e4ngigkeit der Einwohnerzahl <strong>bis sp\u00e4testens 2028<\/strong> abgeschlossen sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ab dann gibt es zwei M\u00f6glichkeiten: <strong>Plant die Gemeinde ein Wasserstoffnetz<\/strong>, d\u00fcrfen Gasheizungen unbeschr\u00e4nkt weiterlaufen und auch neue Anlagen installiert werden. Der kommunale Gasversorger mischt dem Erdgas im ersten Schritt bis zu <strong>20 % Wasserstoff <\/strong>bei. Langfristig ist das Ziel bis<strong> zum 1. Januar 2045 auf 100 % Wasserstoff im Netz <\/strong>umzustellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plant die Gemeinde kein Wasserstoffnetz<\/strong>, k\u00f6nnen Gasheizungen ebenfalls weiterlaufen. <strong>Ab 2029 m\u00fcssen sie dann aber zu mindestens 15 % mit <a href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/glossar\/biomethan\/\">Biomethan<\/a><\/strong> oder Wasserstoff betrieben werden. Neue Gasheizungen d\u00fcrfen auch eingebaut werden. Allerdings m\u00fcssen diese direkt zu 65 % mit erneuerbaren Energien heizen.<sup data-fn=\"e88cf3a7-3317-4227-bd7e-18e70feac973\" class=\"fn\"><a href=\"#e88cf3a7-3317-4227-bd7e-18e70feac973\" id=\"e88cf3a7-3317-4227-bd7e-18e70feac973-link\">4<\/a><\/sup> Auch in diesem Szenario ist das Enddatum f\u00fcr fossile Brennstoffe der 31. Dezember 2044. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend viele Hersteller bereits mit Hochdruck an <strong>H<sub>2<\/sub>-ready-Gasheizungen<\/strong> arbeiten, bietet Viessmann als einer der ersten Hersteller Gas-Brennwertger\u00e4te an, die nach einer Umr\u00fcstung zu <strong><a href=\"https:\/\/www.erdgas-suedwest.de\/zuhause\/heizung\/gasbrennwertheizung?ctm_source=blog&amp;ctm_medium=esw&amp;ctm_campaign=h2-ready-gasheizungen-check&amp;ctm_content=textlink\" rel=\"noreferrer noopener\">100 % mit Wasserstoff betrieben<\/a><\/strong> werden k\u00f6nnen.<sup data-fn=\"f96842a9-63c5-42ad-9048-6cc0ef4bc1cb\" class=\"fn\"><a href=\"#f96842a9-63c5-42ad-9048-6cc0ef4bc1cb\" id=\"f96842a9-63c5-42ad-9048-6cc0ef4bc1cb-link\">5<\/a><\/sup> Hersteller wie Bosch, Buderus, Wolf und Vaillant haben bisher Ger\u00e4te im Angebot, die lediglich <strong>mit bis zu 30 Volumenprozent Wasserstoff-Beimischung<\/strong> arbeiten k\u00f6nnen.<\/p>\n\n\n\n<div id=\"wasserstoff-verfuegbarkeit-preise\" class=\"sprung\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2. Verf\u00fcgbarkeit und Preise von gr\u00fcnem Wasserstoff<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine zweite Herausforderung stellen sowohl die <strong>Verf\u00fcgbarkeit als auch die Preise von gr\u00fcnem Wasserstoff <\/strong>dar. Die Meinungen von Expert*innen, ob und wann sich das in Zukunft \u00e4ndern wird und welche Rolle Wasserstoff bei der Energie- und W\u00e4rmewende spielt, unterscheiden sich zum Teil stark voneinander.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So geht etwa eine Studie<sup data-fn=\"199471e5-cbe7-4987-a4be-4a3f7f6cf9d5\" class=\"fn\"><a href=\"#199471e5-cbe7-4987-a4be-4a3f7f6cf9d5\" id=\"199471e5-cbe7-4987-a4be-4a3f7f6cf9d5-link\">6<\/a><\/sup> des Instituts der deutschen Wirtschaft davon aus, dass die Exportkapazit\u00e4ten der m\u00f6glichen Lieferl\u00e4nder bis 2030 auch dann nicht reichen, wenn sie die gesamte Wasserstoffproduktion ausschlie\u00dflich nach Deutschland liefern. Und auch die Deutsche Energieagentur  dena rechnet mit einem noch weiten Weg bis zum Aufbau einer tragenden Wasserstoffwirtschaft.<sup data-fn=\"ecef0c27-8bc5-42c7-bdac-14d8946a36d0\" class=\"fn\"><a href=\"#ecef0c27-8bc5-42c7-bdac-14d8946a36d0\" id=\"ecef0c27-8bc5-42c7-bdac-14d8946a36d0-link\">7<\/a><\/sup> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dagegen spricht Gerald Linke, Vorstandsvorsitzender des Deutschen Vereins des Gas- und Wasserfaches (DVGW), in der Rheinischen Post von einem gro\u00dfen Potenzial f\u00fcr Wasserstoff aus Deutschland, EU- und Drittl\u00e4ndern. Seiner Meinung nach k\u00f6nnte Wasserstoff bereits ab 2030 den deutschen Prim\u00e4renergiebedarf decken.<sup data-fn=\"10635937-41a8-4c15-8cc5-55e4ff2064b8\" class=\"fn\"><a href=\"#10635937-41a8-4c15-8cc5-55e4ff2064b8\" id=\"10635937-41a8-4c15-8cc5-55e4ff2064b8-link\">8<\/a><\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Damit Wasserstoff auch im Rahmen der W\u00e4rmewende interessant wird, m\u00fcssen sowohl seine Verf\u00fcgbarkeit steigen als auch in diesem Kontext die Preise fallen. Aktuell wird gr\u00fcner Wasserstoff mit bis zu <strong>16 Cent pro Kilowattstunde<\/strong> gehandelt. Wann dieser Preis signifikant sinken wird, ist unklar. Der Wissenschaftliche Dienst im Deutschen Bundestag geht von Produktionskosten von 9 ct\/kWh bis 2050 aus. Das Fraunhofer-Institut sieht schon 2045 als m\u00f6gliches Jahr f\u00fcr das Unterschreiten der Neun-Cent-Marke.<\/p>\n\n\n\n<div id=\"wasserstoff-umstellung-gasverteilnetz\" class=\"sprung\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3. Umstellung des Gasverteilernetzes auf 100 % Wasserstoff<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Zu guter Letzt muss auch das <strong>Gasnetz f\u00fcr den Transport von Wasserstoff vorbereitet <\/strong>werden. Alle Komponenten m\u00fcssen auf ihre Wasserstofftauglichkeit gepr\u00fcft und zum Teil ggf. ausgetauscht werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Angaben der EnBW<sup data-fn=\"dd52cd88-271a-4cd2-91ee-c5f11ac692cd\" class=\"fn\"><a href=\"#dd52cd88-271a-4cd2-91ee-c5f11ac692cd\" id=\"dd52cd88-271a-4cd2-91ee-c5f11ac692cd-link\">9<\/a><\/sup> fallen f\u00fcr die Umr\u00fcstung der bestehenden Erdgasleitungen in Richtung eines Wasserstoffnetzes allerdings nur etwa 10 bis 35 % der Kosten eines kompletten Neubaus an. Eine Investition, die aber erst einmal gemacht werden muss, damit gr\u00fcner Wasserstoff gro\u00dffl\u00e4chig zum Heizen eingesetzt werden kann.<sup data-fn=\"c067b0e3-32cb-4d57-b4bb-92f84f458867\" class=\"fn\"><a href=\"#c067b0e3-32cb-4d57-b4bb-92f84f458867\" id=\"c067b0e3-32cb-4d57-b4bb-92f84f458867-link\">10<\/a><\/sup> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Pilotregionen und lokalen Netzgebieten wird bereits eine Wasserstoffbeimischung in H\u00f6he von bis zu 30 Volumenprozent getestet. <\/p>\n\n\n\n<div id=\"zukunft-h2-ready-gasheizung\" class=\"sprung\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit: Zukunft von H<sub>2<\/sub>-ready-Gasheizungen als spannende Alternative<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Frage, welche Rolle Wasserstoff und damit auch H<sub>2<\/sub>-ready-Gasheizungen am Ende bei der W\u00e4rmewende spielen werden, ist aktuell noch nicht absch\u00e4tzbar. Die Expertenprognosen variieren stark: Forschungsinstitute zweifeln an den zuk\u00fcnftigen Exportkapazit\u00e4ten, w\u00e4hrend der Deutsche Verein des Gas- und Wasserfaches zuversichtlich ist und Wasserstoff ab 2030 als Prim\u00e4renergiequelle sieht. Bis dahin muss noch einiges passieren:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wasserstoffverf\u00fcgbarkeit muss sichergestellt sein, der Kilowattstundenpreis unter 9 Cent fallen und die kommunale W\u00e4rmenetzplanung ausgebaut werden. Mit den Anpassungen im Geb\u00e4udeenergiegesetz hat die Politik den Weg f\u00fcr gr\u00fcnen Wasserstoff geebnet. Nun liegt es an der Industrie, entsprechende Ger\u00e4te auf den Markt zu bringen, und an der kommunalen W\u00e4rmeplanung, den Einsatz von Wasserstoff zu ebnen. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Neuanschaffung einer Heizung werden kurz- und mittelfristig vor allem <strong>W\u00e4rmepumpen, Hybridheizungen oder Pelletheizungen<\/strong> interessant sein. H<sub>2<\/sub>-ready-Gasheizungen, die anfangs mit fossilen Erdgas und sukzessive mit Gr\u00fcnen Gasen betrieben werden, k\u00f6nnen eine wirkliche Alternative darstellen \u2013 sofern die oben genannten Herausforderungen bew\u00e4ltigt werden.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div id=\"sources\" class=\"wp-block-group sources\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Belege<\/strong><\/p>\n\n\n<ol class=\"has-small-font-size wp-block-footnotes\"><li id=\"bba35717-12f7-4773-99a8-959f058267af\"><a href=\"https:\/\/www.umweltbundesamt.de\/daten\/energie\/energieverbrauch-fuer-fossile-erneuerbare-waerme\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.umweltbundesamt.de\/daten\/energie\/energieverbrauch-fuer-fossile-erneuerbare-waerme<\/a> <a href=\"#bba35717-12f7-4773-99a8-959f058267af-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 1 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"1c696975-4cac-4707-a8d5-46a4806ffc8c\"><a href=\"https:\/\/www.bundesregierung.de\/breg-de\/aktuelles\/neues-gebaeudeenergiegesetz-2184942\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.bundesregierung.de\/breg-de\/aktuelles\/neues-gebaeudeenergiegesetz-2184942<\/a> <a href=\"#1c696975-4cac-4707-a8d5-46a4806ffc8c-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 2 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"d8310f31-7bd5-4369-b061-4bcc39ea617a\"><a href=\"https:\/\/gas.info\/gas-im-energiemix\/gebaeude\/neue-heizung\/geg-heizungsgesetz\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/gas.info\/gas-im-energiemix\/gebaeude\/neue-heizung\/geg-heizungsgesetz<\/a> <a href=\"#d8310f31-7bd5-4369-b061-4bcc39ea617a-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 3 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"e88cf3a7-3317-4227-bd7e-18e70feac973\"><a href=\"https:\/\/www.zeit.de\/politik\/deutschland\/2023-06\/waermewende-heizungsgesetz-geg-entwuerfe-einigung\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.zeit.de\/politik\/deutschland\/2023-06\/waermewende-heizungsgesetz-geg-entwuerfe-einigung<\/a> <a href=\"#e88cf3a7-3317-4227-bd7e-18e70feac973-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 4 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"f96842a9-63c5-42ad-9048-6cc0ef4bc1cb\"><a href=\"https:\/\/www.viessmann.family\/de\/newsroom\/loesungsangebot\/viessmann-brennwertgeraete-sind-100-prozent-h2-ready.html\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.viessmann-climatesolutions.com\/de\/wasserstoff\/100-prozent-wasserstoffbetrieb-ab-2025-vorgesehen.html\" target=\"_blank\" rel=\"noreferrer noopener\">Viessmann Brennwertger\u00e4te sind 100%-H2-ready. Hier mehr erfahren!<\/a> <a href=\"#f96842a9-63c5-42ad-9048-6cc0ef4bc1cb-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 5 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"199471e5-cbe7-4987-a4be-4a3f7f6cf9d5\"><a href=\"https:\/\/www.iwkoeln.de\/presse\/pressemitteilungen\/malte-kueper-thilo-schaefer-bundesregierung-verschaetzt-sich-bei-importen-bis-2030.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.iwkoeln.de\/presse\/pressemitteilungen\/malte-kueper-thilo-schaefer-bundesregierung-verschaetzt-sich-bei-importen-bis-2030.html<\/a> <a href=\"#199471e5-cbe7-4987-a4be-4a3f7f6cf9d5-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 6 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"ecef0c27-8bc5-42c7-bdac-14d8946a36d0\">dena Newsmeldung: Ein Jahr nationale Wasserstoffstrategie, 2023 <a href=\"#ecef0c27-8bc5-42c7-bdac-14d8946a36d0-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 7 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"10635937-41a8-4c15-8cc5-55e4ff2064b8\"><a href=\"https:\/\/rp-online.de\/leben\/wohnen\/wasserstoff-lohnen-sich-h2-ready-heizungen-fuer-den-buerger_aid-88542101\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/rp-online.de\/leben\/wohnen\/wasserstoff-lohnen-sich-h2-ready-heizungen-fuer-den-buerger_aid-88542101<\/a> <a href=\"#10635937-41a8-4c15-8cc5-55e4ff2064b8-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 8 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"dd52cd88-271a-4cd2-91ee-c5f11ac692cd\"><a href=\"https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html<\/a> <a href=\"#dd52cd88-271a-4cd2-91ee-c5f11ac692cd-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 9 navigieren\">\u21a9\ufe0e<\/a><\/li><li id=\"c067b0e3-32cb-4d57-b4bb-92f84f458867\"><a href=\"https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html<\/a> <a href=\"#c067b0e3-32cb-4d57-b4bb-92f84f458867-link\" aria-label=\"Zur Fu\u00dfnotenreferenz 10 navigieren\">\u21a9\ufe0e<\/a><\/li><\/ol><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Einbau neuer Gasheizungen sollte nach Pl\u00e4nen der Bundesregierung zuk\u00fcnftig verboten werden. Im aktualisierten Geb\u00e4udeenergiegesetz (GEG) werden die H<sub>2<\/sub>-ready-Gasheizungen als m\u00f6gliche Ausnahmen genannt. Was aber steckt hinter dem Begriff? Was kostet eine H<sub>2<\/sub>-ready-Heizung? Und welches Potenzial hat der Einsatz von Wasserstoff f\u00fcr die W\u00e4rmewende? <\/p>\n","protected":false},"author":4,"featured_media":11354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rating_form_position":"","rating_results_position":"","mr_structured_data_type":"Organization","footnotes":"[{\"content\":\"<a href=\\\"https:\/\/www.umweltbundesamt.de\/daten\/energie\/energieverbrauch-fuer-fossile-erneuerbare-waerme\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.umweltbundesamt.de\/daten\/energie\/energieverbrauch-fuer-fossile-erneuerbare-waerme<\/a>\",\"id\":\"bba35717-12f7-4773-99a8-959f058267af\"},{\"content\":\"<a href=\\\"https:\/\/www.bundesregierung.de\/breg-de\/aktuelles\/neues-gebaeudeenergiegesetz-2184942\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.bundesregierung.de\/breg-de\/aktuelles\/neues-gebaeudeenergiegesetz-2184942<\/a>\",\"id\":\"1c696975-4cac-4707-a8d5-46a4806ffc8c\"},{\"content\":\"<a href=\\\"https:\/\/gas.info\/gas-im-energiemix\/gebaeude\/neue-heizung\/geg-heizungsgesetz\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/gas.info\/gas-im-energiemix\/gebaeude\/neue-heizung\/geg-heizungsgesetz<\/a>\",\"id\":\"d8310f31-7bd5-4369-b061-4bcc39ea617a\"},{\"content\":\"<a href=\\\"https:\/\/www.zeit.de\/politik\/deutschland\/2023-06\/waermewende-heizungsgesetz-geg-entwuerfe-einigung\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.zeit.de\/politik\/deutschland\/2023-06\/waermewende-heizungsgesetz-geg-entwuerfe-einigung<\/a>\",\"id\":\"e88cf3a7-3317-4227-bd7e-18e70feac973\"},{\"content\":\"<a href=\\\"https:\/\/www.viessmann.family\/de\/newsroom\/loesungsangebot\/viessmann-brennwertgeraete-sind-100-prozent-h2-ready.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\"><\/a><a href=\\\"https:\/\/www.viessmann-climatesolutions.com\/de\/wasserstoff\/100-prozent-wasserstoffbetrieb-ab-2025-vorgesehen.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Viessmann Brennwertger\u00e4te sind 100%-H2-ready. Hier mehr erfahren!<\/a>\",\"id\":\"f96842a9-63c5-42ad-9048-6cc0ef4bc1cb\"},{\"content\":\"<a href=\\\"https:\/\/www.iwkoeln.de\/presse\/pressemitteilungen\/malte-kueper-thilo-schaefer-bundesregierung-verschaetzt-sich-bei-importen-bis-2030.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.iwkoeln.de\/presse\/pressemitteilungen\/malte-kueper-thilo-schaefer-bundesregierung-verschaetzt-sich-bei-importen-bis-2030.html<\/a>\",\"id\":\"199471e5-cbe7-4987-a4be-4a3f7f6cf9d5\"},{\"content\":\"dena Newsmeldung: Ein Jahr nationale Wasserstoffstrategie, 2023\",\"id\":\"ecef0c27-8bc5-42c7-bdac-14d8946a36d0\"},{\"content\":\"<a href=\\\"https:\/\/rp-online.de\/leben\/wohnen\/wasserstoff-lohnen-sich-h2-ready-heizungen-fuer-den-buerger_aid-88542101\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/rp-online.de\/leben\/wohnen\/wasserstoff-lohnen-sich-h2-ready-heizungen-fuer-den-buerger_aid-88542101<\/a>\",\"id\":\"10635937-41a8-4c15-8cc5-55e4ff2064b8\"},{\"content\":\"<a href=\\\"https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html<\/a>\",\"id\":\"dd52cd88-271a-4cd2-91ee-c5f11ac692cd\"},{\"content\":\"<a href=\\\"https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\/\/www.enbw.com\/unternehmen\/eco-journal\/wasserstofftransport-nach-baden-wuerttemberg.html<\/a>\",\"id\":\"c067b0e3-32cb-4d57-b4bb-92f84f458867\"}]"},"categories":[66],"tags":[49,19],"class_list":["post-11264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heizung","tag-heizungssanierung","tag-wasserstoff"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft<\/title>\n<meta name=\"description\" content=\"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft\" \/>\n<meta property=\"og:description\" content=\"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/\" \/>\n<meta property=\"og:site_name\" content=\"nat\u00fcrlichZukunft\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T13:02:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T14:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sigmund Staus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sigmund Staus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/\"},\"author\":{\"name\":\"Sigmund Staus\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#\\\/schema\\\/person\\\/c6031b6f4675b6a3432d612a62db9870\"},\"headline\":\"H2-ready-Gasheizungen im Check\",\"datePublished\":\"2023-12-13T13:02:42+00:00\",\"dateModified\":\"2025-12-19T14:26:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/\"},\"wordCount\":1634,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/h2-ready-heizungen-wasserstoff-gasnetz.jpg\",\"keywords\":[\"Heizungssanierung\",\"Wasserstoff\"],\"articleSection\":[\"Heizung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/\",\"name\":\"H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/h2-ready-heizungen-wasserstoff-gasnetz.jpg\",\"datePublished\":\"2023-12-13T13:02:42+00:00\",\"dateModified\":\"2025-12-19T14:26:25+00:00\",\"description\":\"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/h2-ready-heizungen-wasserstoff-gasnetz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/h2-ready-heizungen-wasserstoff-gasnetz.jpg\",\"width\":1440,\"height\":530,\"caption\":\"Wasserstoff-Gasnetz f\u00fcr den Betrieb von H2-ready-Gasheizungen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/h2-ready-gasheizungen-check\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H2-ready-Gasheizungen im Check\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#website\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/\",\"name\":\"nat\u00fcrlichZukunft\",\"description\":\"so geht \u00f6kologische Energie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#organization\",\"name\":\"nat\u00fcrlichZukunft\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/natuerlichZukunft_Schriftzug.png\",\"contentUrl\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/natuerlichZukunft_Schriftzug.png\",\"width\":520,\"height\":107,\"caption\":\"nat\u00fcrlichZukunft\"},\"image\":{\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/#\\\/schema\\\/person\\\/c6031b6f4675b6a3432d612a62db9870\",\"name\":\"Sigmund Staus\",\"url\":\"https:\\\/\\\/www.erdgas-suedwest.de\\\/natuerlichzukunft\\\/author\\\/sigmundstaus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft","description":"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/","og_locale":"de_DE","og_type":"article","og_title":"H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft","og_description":"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.","og_url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/","og_site_name":"nat\u00fcrlichZukunft","article_published_time":"2023-12-13T13:02:42+00:00","article_modified_time":"2025-12-19T14:26:25+00:00","og_image":[{"width":1440,"height":530,"url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg","type":"image\/jpeg"}],"author":"Sigmund Staus","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sigmund Staus","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#article","isPartOf":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/"},"author":{"name":"Sigmund Staus","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#\/schema\/person\/c6031b6f4675b6a3432d612a62db9870"},"headline":"H2-ready-Gasheizungen im Check","datePublished":"2023-12-13T13:02:42+00:00","dateModified":"2025-12-19T14:26:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/"},"wordCount":1634,"commentCount":0,"publisher":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#organization"},"image":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg","keywords":["Heizungssanierung","Wasserstoff"],"articleSection":["Heizung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/","name":"H2-ready-Gasheizungen im Check - nat\u00fcrlichZukunft","isPartOf":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#primaryimage"},"image":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg","datePublished":"2023-12-13T13:02:42+00:00","dateModified":"2025-12-19T14:26:25+00:00","description":"Welches Potenzial hat Wasserstoff beim Heizen? Funktion, Kosten und Voraussetzungen der H2-ready-Technologie im \u00dcberblick.","breadcrumb":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#primaryimage","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg","contentUrl":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2023\/12\/h2-ready-heizungen-wasserstoff-gasnetz.jpg","width":1440,"height":530,"caption":"Wasserstoff-Gasnetz f\u00fcr den Betrieb von H2-ready-Gasheizungen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/h2-ready-gasheizungen-check\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/"},{"@type":"ListItem","position":2,"name":"H2-ready-Gasheizungen im Check"}]},{"@type":"WebSite","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#website","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/","name":"nat\u00fcrlichZukunft","description":"so geht \u00f6kologische Energie","publisher":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#organization","name":"nat\u00fcrlichZukunft","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#\/schema\/logo\/image\/","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2024\/04\/natuerlichZukunft_Schriftzug.png","contentUrl":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-content\/uploads\/2024\/04\/natuerlichZukunft_Schriftzug.png","width":520,"height":107,"caption":"nat\u00fcrlichZukunft"},"image":{"@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/#\/schema\/person\/c6031b6f4675b6a3432d612a62db9870","name":"Sigmund Staus","url":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/author\/sigmundstaus\/"}]}},"multi-rating":{"mr_rating_results":[{"adjusted_star_result":4.69,"star_result":4.69,"total_max_option_value":5,"adjusted_score_result":4.69,"score_result":4.69,"percentage_result":93.75,"adjusted_percentage_result":93.75,"count":16,"post_id":11264}]},"_links":{"self":[{"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/posts\/11264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/comments?post=11264"}],"version-history":[{"count":57,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/posts\/11264\/revisions"}],"predecessor-version":[{"id":15493,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/posts\/11264\/revisions\/15493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/media\/11354"}],"wp:attachment":[{"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/media?parent=11264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/categories?post=11264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erdgas-suedwest.de\/natuerlichzukunft\/wp-json\/wp\/v2\/tags?post=11264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}